{"id":9509,"date":"2019-08-13T11:30:57","date_gmt":"2019-08-13T09:30:57","guid":{"rendered":"https:\/\/www.wespeakiot.com\/?p=9509"},"modified":"2019-08-13T11:56:24","modified_gmt":"2019-08-13T09:56:24","slug":"tata-motors-elektrifiziert-indien","status":"publish","type":"post","link":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/","title":{"rendered":"Tata Motors elektrifiziert Indien"},"content":{"rendered":"<div class=\"ccfic\"><span class=\"ccfic-text\">Foto: Tata Motors\/Tata Power - <\/span> <span class=\"ccfic-source\">Stromtankstelle (Ramesh Subramanyam (CFO & President Tata Power), Mr Shaile<\/span><\/div>\n<h2>W\u00e4hrend Fortschritte des <a href=\"https:\/\/www.lemonbeat.de\/smart-energy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Smart Grids<\/a> in Deutschland &#8211; und der allgemeine Ausbau neuer e-Infrastruktur &#8211; ausgebremst durch viel Regulierung und zur\u00fcckhaltende Unternehmen h\u00f6chstens als \u201ez\u00f6gerlich\u201c beschrieben werden k\u00f6nnen, geht es in anderen L\u00e4ndern mit gr\u00f6\u00dferen Schritten voran.<\/h2>\n<p>So hat <a href=\"https:\/\/www.tatamotors.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tata Motors<\/a> k\u00fcrzlich angek\u00fcndigt, bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge in Zusammenarbeit mit ihrem Schwesterunternehmen <a href=\"https:\/\/www.tatapower.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tata Power<\/a> zu bauen.<\/p>\n<p>Zu den in einem ersten Schritt \u201eelektrifizierten\u201c St\u00e4dten geh\u00f6ren Delhi, Mumbai, Pune, Hyderabad und Bengaluru. Die Installation der ersten sieben Ladestationen in Pune hat bereits begonnen. Die n\u00e4chsten 45 Ladestationen werden in den kommenden Monaten gebaut.<\/p>\n<p>Die ersten 50 Ger\u00e4te werden 15kW-Ladeger\u00e4te sein und dem bestehenden Bharat-Standard entsprechen &#8211; der Bharat DC-001 entspricht einer Industriesteckdose nach <a href=\"https:\/\/de.wikipedia.org\/wiki\/IEC_60309\" target=\"_blank\" rel=\"noopener noreferrer\">IEC 60309<\/a>.<\/p>\n<p>[<em>Bharat stage Emission Standards (BSES &#8211; \u201eBharat Stufen Emissionsstandards\u201c) sind von der indischen Regierung eingef\u00fchrte Emissionsstandards zur Regulierung der Emission von Luftschadstoffen aus Verbrennungsmotoren und Ausr\u00fcstungen f\u00fcr Fremdz\u00fcndungsmotoren, einschlie\u00dflich Kraftfahrzeugen. Die Standards und der Zeitplan f\u00fcr die Umsetzung werden vom Central Pollution Control Board unter dem Ministerium f\u00fcr Umwelt, Wald und Klimawandel festgelegt. Die Normen, die auf europ\u00e4ischen Vorschriften basieren, wurden erstmals im Jahr 2000 eingef\u00fchrt.<\/em> [\u2026] \u2013 Quelle: <a href=\"https:\/\/en.wikipedia.org\/wiki\/Bharat_Stage_emission_standards\" target=\"_blank\" rel=\"noopener noreferrer\">Wikipedia<\/a>]<\/p>\n<p>Die restlichen 250 Ladeger\u00e4te mit 30 bis 50 kW werden mit dem CCS2-Anschluss ausgestattet, der auch in Europa weit verbreitet ist.<\/p>\n<h3>Globale Standards an Indischen e-Tankstellen<\/h3>\n<p>Laut lokalen Medienberichten hat die indische Regierung im Juli beschlossen, neben dem heimischen Bharat-Standard auch CHAdeMO- und CCS-Ladestationen zu bauen &#8211; der ebenfalls seit einiger Zeit diskutierte GB\/T-Standard aus China kommt offensichtlich nicht zum Einsatz. Tata scheint sich jedoch f\u00fcr den CCS-Standard entschieden zu haben, was einen m\u00f6glichen zuk\u00fcnftigen Export der indischen Technologie auch in andere L\u00e4nder erm\u00f6glichen wird.<\/p>\n<p>Dieser Netzausbau scheint auch ein Hinweis auf die baldige Einf\u00fchrung der kommenden <a href=\"https:\/\/www.wespeakiot.com\/de\/selbstfahrende-autos\/\" target=\"_blank\" rel=\"noopener noreferrer\">Elektroautos<\/a> des Tata Konzerns zu sein. Tata bietet derzeit nur den Tigor EV an, von dem es eine h\u00f6herwertige Version geben wird. Es wird auch elektrische Versionen der Tata-Modelle Nexon und Altroz geben.W\u00e4hrend europ\u00e4ische Anbieter und Hersteller sich zur\u00fcckhaltend auf den Premium-Markt konzentrieren; h\u00f6chstens \u00fcberteuerte, viel zu schwere, umweltbelastende SUVs und Sportwagen vorstellen, hat Tata Motors unl\u00e4ngst vier neue Elektromodelle vorgestellt, die innerhalb der n\u00e4chsten 18 Monate f\u00fcr den indischen Markt eingef\u00fchrt werden sollen.<\/p>\n<p>Das Verhalten der deutschen und europ\u00e4ischen Automobilhersteller darf im Vergleich durchaus &#8222;kontraproduktiv&#8220; genannt, wenn nicht nicht gar als &#8222;destruktiv&#8220; bezeichnet werden. Zwar sollen neue Standorte im produktionsg\u00fcnstigeren nicht-EU-Ausland er\u00f6ffnet werden (wie unl\u00e4ngst durch VW), bessere Preise f\u00fcr die Verbraucher; oder gar innovative, kleinere, sparsame (e)-Autos wurden nicht in Aussicht gestellt.<\/p>\n<p>Die Verf\u00fcgbarkeit hochwertiger aber bezahlbarer e-Automobile auch in Deutschland und der EU w\u00fcrde nicht nur dazu beitragen, Klimaschutzziele zu erreichen &#8211; sie w\u00fcrde eben auch den dringend angebrachten Aus- und\u00a0 Umbau verhandener Netze beschleunigen, alternative Energieerzeugung f\u00f6rdern und gar durch die damit verbundene Steigerung der Attraktivit\u00e4t von Kleinerzeuger-Anlagen zu begr\u00fc\u00dfenswerten strukturellen Ver\u00e4nderungen beitragen.<\/p>\n<p>&#8222;<strong><em>Wir verpflichten uns, India EV im Einklang mit dem Bestreben der Regierung, umweltfreundliche Technologiel\u00f6sungen anzubieten, und der Vision der Tata Group, den CO2-Fu\u00dfabdruck Indiens zu reduzieren, bereit zu stellen. Unser Ziel ist es, das Aufladen von EV so schnell und einfach wie m\u00f6glich f\u00fcr alle Inder zu gestalten, und wir freuen uns sehr \u00fcber die Partnerschaft mit Tata Motors, mit der wir gemeinsam hochrangige Standorte identifiziert haben, die von den potenziellen EV-Besitzern bevorzugt werden k\u00f6nnten<\/em><\/strong>&#8222;. &#8211; Praveer Sinha, Gesch\u00e4ftsf\u00fchrer &amp; CEO Tata Power<\/p>\n<h3>Gleichstrom in Indien derzeit noch unbedeutend<\/h3>\n<p>Die Gleichstrom-Schnellladung spielt in Indien derzeit noch eine untergeordnete Rolle, daher ist die Ladeleistung im europ\u00e4ischen Vergleich gering. Die \u00fcberwiegende Mehrheit der Elektrofahrzeuge in Indien sind Zwei- und Dreir\u00e4der, f\u00fcr die Schnellladetechnologien wirtschaftlich nicht sinnvoll sind. Diese werden in der Regel an den landes\u00fcblichen 15-Ampere-Steckdosen abgerechnet.<\/p>\n<p>Es bleibt abzuwarten, ob die fortschreitenden Entwicklungen und infrastrukturellen Ausbauma\u00dfnahmen in anderen L\u00e4ndern auch in Deutschland ankommen werden &#8211; oder diese weiterhin durch \u00dcberregulierung oder mangelndem Mut zum Fortschritt ausgebremst werden. Nur wenige Anbieter, wie <a href=\"https:\/\/news.innogy.com\/rekordzusage-1245-neue-ladesaulen-bei-innogy\/\" target=\"_blank\" rel=\"noopener noreferrer\">beispielsweise Innogy SE<\/a> in Kooperation mit zahlreichen Stadtwerken und dem Bundesministerium f\u00fcr Verkehr und digitale Infrastruktur (BMVI), investieren derzeit in den Ausbau eines Smart Grids; verkn\u00fcpfen dabei neue Technologie u.a. auch mit dem <a href=\"http:\/\/www.wespeakiot.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Internet der Dinge<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.<\/p>\n","protected":false},"author":24,"featured_media":9523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2360],"tags":[7758,7759,6239,6287,6379,7757,7760],"class_list":["post-9509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlagzeilen","tag-e-auto","tag-innogy-se","tag-iot-de","tag-lemonbeat-de","tag-smart-energy-de","tag-smart-grind","tag-tata-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tata Motors elektrifiziert Indien - We speak IoT<\/title>\n<meta name=\"description\" content=\"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tata Motors elektrifiziert Indien - We speak IoT\" \/>\n<meta property=\"og:description\" content=\"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/\" \/>\n<meta property=\"og:site_name\" content=\"We speak IoT\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-13T09:30:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-13T09:56:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Editorial Staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editorial Staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/\"},\"author\":{\"name\":\"Editorial Staff\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#\\\/schema\\\/person\\\/f7fc26ad99702ff175fe7dc16d590925\"},\"headline\":\"Tata Motors elektrifiziert Indien\",\"datePublished\":\"2019-08-13T09:30:57+00:00\",\"dateModified\":\"2019-08-13T09:56:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/\"},\"wordCount\":746,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Tata.jpg\",\"keywords\":[\"e-Auto\",\"Innogy SE\",\"IoT\",\"Lemonbeat\",\"Smart Energy\",\"Smart Grind\",\"Tata\"],\"articleSection\":[\"Schlagzeilen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/\",\"name\":\"Tata Motors elektrifiziert Indien - We speak IoT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Tata.jpg\",\"datePublished\":\"2019-08-13T09:30:57+00:00\",\"dateModified\":\"2019-08-13T09:56:24+00:00\",\"description\":\"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Tata.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/Tata.jpg\",\"width\":960,\"height\":640,\"caption\":\"Tata\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/tata-motors-elektrifiziert-indien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tata Motors elektrifiziert Indien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/\",\"name\":\"WeSpeakIoT\",\"description\":\"Inside the Internet of Things\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#organization\",\"name\":\"WeSpeakIoT - Inside the Internet of Things\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wespeakiot-logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/wespeakiot-logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"WeSpeakIoT - Inside the Internet of Things\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/#\\\/schema\\\/person\\\/f7fc26ad99702ff175fe7dc16d590925\",\"name\":\"Editorial Staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/wsi_logo_black-100x100.jpg\",\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/wsi_logo_black-100x100.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wespeakiot.com\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/wsi_logo_black-100x100.jpg\",\"caption\":\"Editorial Staff\"},\"url\":\"https:\\\/\\\/www.wespeakiot.com\\\/de\\\/author\\\/estaff\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tata Motors elektrifiziert Indien - We speak IoT","description":"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/","og_locale":"de_DE","og_type":"article","og_title":"Tata Motors elektrifiziert Indien - We speak IoT","og_description":"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.","og_url":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/","og_site_name":"We speak IoT","article_published_time":"2019-08-13T09:30:57+00:00","article_modified_time":"2019-08-13T09:56:24+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg","type":"image\/jpeg"}],"author":"Editorial Staff","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Editorial Staff","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#article","isPartOf":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/"},"author":{"name":"Editorial Staff","@id":"https:\/\/www.wespeakiot.com\/de\/#\/schema\/person\/f7fc26ad99702ff175fe7dc16d590925"},"headline":"Tata Motors elektrifiziert Indien","datePublished":"2019-08-13T09:30:57+00:00","dateModified":"2019-08-13T09:56:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/"},"wordCount":746,"commentCount":0,"publisher":{"@id":"https:\/\/www.wespeakiot.com\/de\/#organization"},"image":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg","keywords":["e-Auto","Innogy SE","IoT","Lemonbeat","Smart Energy","Smart Grind","Tata"],"articleSection":["Schlagzeilen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/","url":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/","name":"Tata Motors elektrifiziert Indien - We speak IoT","isPartOf":{"@id":"https:\/\/www.wespeakiot.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#primaryimage"},"image":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg","datePublished":"2019-08-13T09:30:57+00:00","dateModified":"2019-08-13T09:56:24+00:00","description":"Tata Motors baut bis Ende des Gesch\u00e4ftsjahres 2020 in f\u00fcnf indischen Gro\u00dfst\u00e4dten insgesamt 300 smarte Ladestationen f\u00fcr Elektrofahrzeuge.","breadcrumb":{"@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#primaryimage","url":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg","contentUrl":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2019\/08\/Tata.jpg","width":960,"height":640,"caption":"Tata"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wespeakiot.com\/de\/tata-motors-elektrifiziert-indien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.wespeakiot.com\/de\/"},{"@type":"ListItem","position":2,"name":"Tata Motors elektrifiziert Indien"}]},{"@type":"WebSite","@id":"https:\/\/www.wespeakiot.com\/de\/#website","url":"https:\/\/www.wespeakiot.com\/de\/","name":"WeSpeakIoT","description":"Inside the Internet of Things","publisher":{"@id":"https:\/\/www.wespeakiot.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wespeakiot.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.wespeakiot.com\/de\/#organization","name":"WeSpeakIoT - Inside the Internet of Things","url":"https:\/\/www.wespeakiot.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wespeakiot.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2025\/08\/wespeakiot-logo-696x696-1.jpg","contentUrl":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2025\/08\/wespeakiot-logo-696x696-1.jpg","width":696,"height":696,"caption":"WeSpeakIoT - Inside the Internet of Things"},"image":{"@id":"https:\/\/www.wespeakiot.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.wespeakiot.com\/de\/#\/schema\/person\/f7fc26ad99702ff175fe7dc16d590925","name":"Editorial Staff","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2017\/07\/wsi_logo_black-100x100.jpg","url":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2017\/07\/wsi_logo_black-100x100.jpg","contentUrl":"https:\/\/www.wespeakiot.com\/wp-content\/uploads\/2017\/07\/wsi_logo_black-100x100.jpg","caption":"Editorial Staff"},"url":"https:\/\/www.wespeakiot.com\/de\/author\/estaff\/"}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","cc_featured_image_caption":{"caption_text":"Foto: Tata Motors\/Tata Power - ","source_text":"Stromtankstelle (Ramesh Subramanyam (CFO & President Tata Power), Mr Shaile","source_url":""},"_links":{"self":[{"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/posts\/9509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/comments?post=9509"}],"version-history":[{"count":0,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/posts\/9509\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/media\/9523"}],"wp:attachment":[{"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/media?parent=9509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/categories?post=9509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wespeakiot.com\/de\/wp-json\/wp\/v2\/tags?post=9509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}